{"id":95,"date":"2026-07-03T16:28:18","date_gmt":"2026-07-03T22:28:18","guid":{"rendered":"https:\/\/gravitalfilmfest.com\/proyectosocial\/?page_id=95"},"modified":"2026-07-03T16:28:18","modified_gmt":"2026-07-03T22:28:18","slug":"contribuye","status":"publish","type":"page","link":"https:\/\/gravitalfilmfest.com\/proyectosocial\/contribuye\/","title":{"rendered":"CONTRIBUYE"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Toda contribuci\u00f3n ayuda a preservar una parte de esta historia.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Archivo Hist\u00f3rico del <strong>Sal\u00f3n de las Almas Torturadas bajo la Luz Roja<\/strong> es un proyecto permanente de investigaci\u00f3n, conservaci\u00f3n y difusi\u00f3n del patrimonio fotogr\u00e1fico construido a lo largo de los a\u00f1os por alumnos, maestros, colaboradores y amigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada fotograf\u00eda recuperada, cada documento conservado, cada pieza restaurada y cada recuerdo compartido contribuyen a preservar una historia que de otra manera podr\u00eda perderse con el paso del tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si deseas apoyar este proyecto, existen muchas formas de hacerlo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\">Puedes contribuir de muchas maneras<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83d\udcf7 Fotograf\u00edas y material hist\u00f3rico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si conservas fotograf\u00edas, negativos, diapositivas, impresiones, documentos, carteles, reconocimientos, invitaciones, cartas o cualquier otro material relacionado con la historia del proyecto, nos gustar\u00eda conocerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El material puede ser donado o prestado temporalmente para su digitalizaci\u00f3n y posterior devoluci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83c\udfa5 Testimonios y recuerdos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si fuiste alumno, maestro, colaborador, visitante o participaste en alguna actividad relacionada con el Sal\u00f3n de las Almas Torturadas bajo la Luz Roja o con Gravital, tu testimonio tambi\u00e9n forma parte de esta historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los recuerdos personales ayudan a reconstruir acontecimientos que muchas veces no quedaron registrados en documentos o fotograf\u00edas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83d\udcf7 Equipo fotogr\u00e1fico y de laboratorio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n recibimos c\u00e1maras fotogr\u00e1ficas, lentes, ampliadoras, tanques de revelado, temporizadores, accesorios, mobiliario, herramientas y cualquier otro equipo relacionado con la fotograf\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No importa si el equipo funciona o presenta da\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas piezas pueden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>incorporarse a la Colecci\u00f3n Patrimonial SAT;<\/li>\n\n\n\n<li>restaurarse para volver a utilizarse con fines educativos;<\/li>\n\n\n\n<li>utilizarse como material de estudio;<\/li>\n\n\n\n<li>servir como fuente de refacciones para conservar otros equipos hist\u00f3ricos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cada pieza puede contribuir al crecimiento del laboratorio y a la preservaci\u00f3n del patrimonio fotogr\u00e1fico.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83d\udc99 Apoyo al desarrollo del proyecto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es posible contribuir mediante apoyo econ\u00f3mico destinado exclusivamente al fortalecimiento de las actividades del proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas contribuciones pueden ayudar, entre otras cosas, a la adquisici\u00f3n de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>papel fotogr\u00e1fico;<\/li>\n\n\n\n<li>pel\u00edcula fotogr\u00e1fica;<\/li>\n\n\n\n<li>productos qu\u00edmicos para laboratorio;<\/li>\n\n\n\n<li>materiales de conservaci\u00f3n;<\/li>\n\n\n\n<li>equipo especializado;<\/li>\n\n\n\n<li>herramientas;<\/li>\n\n\n\n<li>insumos para restauraci\u00f3n;<\/li>\n\n\n\n<li>materiales educativos;<\/li>\n\n\n\n<li>infraestructura para el Archivo Hist\u00f3rico.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cada aportaci\u00f3n, sin importar su tama\u00f1o, representa una inversi\u00f3n directa en la conservaci\u00f3n y difusi\u00f3n del patrimonio fotogr\u00e1fico.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83e\udd1d Trabajo voluntario<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puedes contribuir compartiendo tus conocimientos, ayudando a identificar personas o lugares presentes en fotograf\u00edas hist\u00f3ricas, colaborando en investigaciones documentales o apoyando actividades relacionadas con la preservaci\u00f3n del Archivo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\">Nuestro compromiso<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Todo el material recibido ser\u00e1 cuidadosamente revisado, documentado y verificado antes de incorporarse al Archivo Hist\u00f3rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada contribuci\u00f3n ser\u00e1 tratada con respeto y responsabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el colaborador as\u00ed lo decida, su participaci\u00f3n podr\u00e1 ser reconocida p\u00fablicamente; si prefiere permanecer en el anonimato, su decisi\u00f3n ser\u00e1 respetada.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfC\u00f3mo puedo contribuir?<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente puedes ponerte en contacto con nosotros mediante:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>WhatsApp<\/li>\n\n\n\n<li>Redes sociales oficiales<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En el futuro incorporaremos otros medios de contacto conforme el proyecto contin\u00fae creciendo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\">Gracias<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Archivo Hist\u00f3rico es una obra en permanente construcci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada fotograf\u00eda recuperada, cada documento conservado, cada pieza restaurada y cada historia compartida ayudan a preservar la memoria del <strong>Sal\u00f3n de las Almas Torturadas bajo la Luz Roja<\/strong> para las generaciones futuras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Toda contribuci\u00f3n ayuda a preservar una parte de esta historia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toda contribuci\u00f3n ayuda a preservar una parte de esta historia. El Archivo Hist\u00f3rico del Sal\u00f3n de las Almas Torturadas bajo la Luz Roja es un proyecto permanente de investigaci\u00f3n, conservaci\u00f3n y difusi\u00f3n del patrimonio fotogr\u00e1fico construido a lo largo de los a\u00f1os por alumnos, maestros, colaboradores y amigos. Cada fotograf\u00eda recuperada, cada documento conservado, cada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-95","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/pages\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":1,"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/pages\/95\/revisions"}],"predecessor-version":[{"id":96,"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/pages\/95\/revisions\/96"}],"wp:attachment":[{"href":"https:\/\/gravitalfilmfest.com\/proyectosocial\/wp-json\/wp\/v2\/media?parent=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}